{"id":1777,"date":"2019-07-05T08:48:40","date_gmt":"2019-07-05T08:48:40","guid":{"rendered":"https:\/\/cde.nus.edu.sg\/arch\/?page_id=1777"},"modified":"2024-07-10T15:02:47","modified_gmt":"2024-07-10T07:02:47","slug":"current-students","status":"publish","type":"page","link":"https:\/\/cde.nus.edu.sg\/arch\/why-doa\/current-students\/","title":{"rendered":"Current Students"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":130,"featured_media":0,"parent":1755,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-1777","page","type-page","status-publish","hentry","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/pages\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/users\/130"}],"replies":[{"embeddable":true,"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":10,"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/pages\/1777\/revisions"}],"predecessor-version":[{"id":12486,"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/pages\/1777\/revisions\/12486"}],"up":[{"embeddable":true,"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/pages\/1755"}],"wp:attachment":[{"href":"https:\/\/cde.nus.edu.sg\/arch\/wp-json\/wp\/v2\/media?parent=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}